{"id":5982,"date":"2021-09-06T09:56:14","date_gmt":"2021-09-06T09:56:14","guid":{"rendered":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/?p=5982"},"modified":"2021-09-06T10:03:47","modified_gmt":"2021-09-06T10:03:47","slug":"nos-seduce-y-fascina-el-poder","status":"publish","type":"post","link":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/2021\/09\/06\/nos-seduce-y-fascina-el-poder\/","title":{"rendered":"NOS SEDUCE Y FASCINA EL PODER"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/files\/2021\/09\/grupo-jovenes-estudiantes-felices-universidad_85574-4531-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/files\/2021\/09\/grupo-jovenes-estudiantes-felices-universidad_85574-4531-1.jpg\" alt=\"\" class=\"wp-image-5983\" width=\"504\" height=\"336\" srcset=\"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/files\/2021\/09\/grupo-jovenes-estudiantes-felices-universidad_85574-4531-1.jpg 626w, https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/files\/2021\/09\/grupo-jovenes-estudiantes-felices-universidad_85574-4531-1-580x386.jpg 580w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/a><\/figure>\n\n\n\n<p>Nos decoramos para ser atractivos,<br>y as\u00ed poder codearnos con el decorado,<br>porque en definitiva, a todos, feos y guapos,<br>nos gusta gustar.<\/p>\n\n\n\n<p>Estudiamos, trabajamos, sacrificamos nuestro tiempo libre,<br>para luego poder trabajar lo menos posible,<br>porque en definitiva,<br>a todos nos pone cachondos el ocio<br>a largo plazo.<\/p>\n\n\n\n<p>Pensamos y desarrollamos las teor\u00edas m\u00e1s complejas,<br>bailamos, cantamos, componemos las mejores canciones,<br>proyectamos, dise\u00f1amos, escribimos,<br>componemos los mejores textos,<br>para luego poder follar m\u00e1s y mejor,<br>porque en definitiva, a todos nos gusta<br>el sexo.<\/p>\n\n\n\n<p>Poder para luego joder.<br>Nos seduce y fascina el poder.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos decoramos para ser atractivos,y as\u00ed poder codearnos con el decorado,porque en definitiva, a todos, feos y guapos,nos gusta gustar. Estudiamos, trabajamos, sacrificamos nuestro tiempo libre,para luego poder trabajar lo menos posible,porque en definitiva,a todos nos pone cachondos el ocioa largo plazo. Pensamos y desarrollamos las teor\u00edas m\u00e1s complejas,bailamos, cantamos, componemos las mejores canciones,proyectamos, dise\u00f1amos, &hellip; <a href=\"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/2021\/09\/06\/nos-seduce-y-fascina-el-poder\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">NOS SEDUCE Y FASCINA EL PODER<\/span><\/a><\/p>\n","protected":false},"author":89,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5982","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/posts\/5982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/comments?post=5982"}],"version-history":[{"count":3,"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/posts\/5982\/revisions"}],"predecessor-version":[{"id":5986,"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/posts\/5982\/revisions\/5986"}],"wp:attachment":[{"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/media?parent=5982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/categories?post=5982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.noticiasdenavarra.com\/lacurvadelsigloXXI\/wp-json\/wp\/v2\/tags?post=5982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}