{"id":76,"date":"2014-12-26T11:30:25","date_gmt":"2014-12-26T11:30:25","guid":{"rendered":"http:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/?p=76"},"modified":"2014-12-25T19:09:27","modified_gmt":"2014-12-25T19:09:27","slug":"la-creatividad-esta-sobrevalorada-2","status":"publish","type":"post","link":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/2014\/12\/26\/la-creatividad-esta-sobrevalorada-2\/","title":{"rendered":"LA CREATIVIDAD EST\u00c1 SOBREVALORADA"},"content":{"rendered":"<p>\u00ab<em>\u00bfMe contradigo?, s\u00ed, me contradigo. Soy muchos, contengo multitudes<\/em>\u00ab.<\/p>\n<p>(Walt Whitman)<\/p>\n<p style=\"text-align: left\">A punto de abandonar este ya viejo a\u00f1o 2014 en el que la cultura ha pasado de estar en un coma de primer estadio a sufrir un coma profundo, una vuelve a descubrir con una mezcla de estupor y mala leche que los peri\u00f3dicos, suplementos y blogs varios vuelven a llenar sus p\u00e1ginas con la que yo ya he denominado \u201cla enfermedad cultureta de fin de a\u00f1o\u201d. \u00bfY en qu\u00e9 consiste dicha patolog\u00eda? En algo tan aburrido, cansino y pedante como las famosas listas de lo m\u00e1s entre lo m\u00e1s. Lista de los mejores discos, las mejores canciones, los mejores int\u00e9rpretes, las mejores exposiciones, los mejores artistas, los mejores museos, los mejores comisarios, en definitiva, los mejores entre los mejores.<\/p>\n<p style=\"text-align: left\"><a href=\"http:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/files\/2014\/12\/street-art-creativo-060_thumb.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-77\" src=\"http:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/files\/2014\/12\/street-art-creativo-060_thumb-580x639.jpg\" alt=\"street-art-creativo-060_thumb\" width=\"395\" height=\"434\" \/><\/a>No me entiendan mal. No digo que los que est\u00e9n en esas listas no lo merezcan sino que los que lo merecen nunca suelen estar en ellas. Somos un pa\u00eds de cantidad que no de calidad y por ello poner n\u00famero a la cultura es algo que nos apasiona. Sin embargo, en este \u00faltimo a\u00f1o en el que el famoso dicho de \u201ctrabajar por amor al arte\u201d se ha hecho tan literal que duele s\u00f3lo de o\u00edrlo es necesario valorar fuera de esas listas de \u201clos cuarenta principales de la cultura\u201d a esos m\u00fasicos que se siguen partiendo los cuernos por sonar bien en locales de segunda, a esos comisarios que trabajan d\u00eda y noche en exposiciones en las que su sue\u00f1o principal es ganar lo justo para comer, a esos directores de peque\u00f1os museos que hacen encaje de bolillos para pagar las facturas de la luz sin dejar de pagar a sus t\u00e9cnicos, a esos educadores que no pierden la sonrisa en los talleres y visitas pese al agotamiento de caminar siempre en la precariedad laboral, a esos artistas que dedican una hora al trabajo de estudio y ocho a navegar por internet en busca de becas que les ayuden a sobrevivir, a esos que alimentan las redes sociales de buenos art\u00edculos y comentarios por los que casi nunca cobran, y tantos y tantas, y tantas y tantos.<\/p>\n<p style=\"text-align: left\">En este campo de batalla en el que se ha convertido el mundo de la cultura podr\u00edamos llegar a pensar que s\u00f3lo el buen oficio y la perseverancia lograr\u00e1n que la calidad siga existiendo por encima de la cantidad. Sin embargo, existe otro aspecto que es para m\u00ed m\u00e1s importante que los anteriores. Un aspecto en ocasiones malentendido y en muchas infravalorado: la creatividad. En franc\u00e9s, para indicar que alguien es un so\u00f1ador, que construye castillos en el aire, se dice <em>faire des chateaux en Espagne<\/em>. La creatividad ha estado siempre relacionada con los so\u00f1adores y estos con la locura. Este pa\u00eds ha demostrado con creces ser un pa\u00eds de mangantes y farsantes pero, afortunadamente, tambi\u00e9n sigue siendo un pa\u00eds de so\u00f1adores. Y en estos momentos la salvaci\u00f3n de la cultura pasa por una mezcla de cordura y locura. S\u00f3lo las mentes abiertas, flexibles, pasionales y, en definitiva, creativas ser\u00e1n capaces de sobrevivir a este aniquilamiento\u00a0cultural.<\/p>\n<p style=\"text-align: left\">No cabe duda de que la creatividad puede suponer para muchos un signo de extravagancia. Y todos sabemos que la extravagancia no est\u00e1 bien vista en esta sociedad globalizada en la que (con)vivimos. Pero la acci\u00f3n creativa es la \u00fanica capaz de transformar, tal como dec\u00eda Whitman, lo \u00fanico en m\u00faltiple y es ese el escenario que nos ayudar\u00e1 a avanzar. La acci\u00f3n que produce transformaci\u00f3n es la \u00fanica que tiene verdadera validez y es la que necesitamos con verdadera urgencia.<\/p>\n<p style=\"text-align: left\">En los \u00faltimos tiempos, el mundo de la empresa ha puesto de moda un t\u00e9rmino que me enerva tanto como gran parte de esos empresarios: \u201creinventarse\u201d. \u00bfY qu\u00e9 significa reinventarse? Reinventarse para la mayor\u00eda de los que mueven los hilos no significa otra cosa que adaptarse a sus necesidades. Me viene a la memoria la famosa frase que Don Fabrizio, Pr\u00edncipe de Salina, pronuncia en Gattopardo: \u201cSi queremos que todo siga como est\u00e1, es necesario que todo cambie\u201d. Ante unos horarios de trabajo interminables, unas condiciones econ\u00f3micas insufribles, una negaci\u00f3n inmoral de recursos p\u00fablicos y un desinter\u00e9s insultante hacia el mundo de la educaci\u00f3n, se nos \u201cinvita\u201d, en una suerte de fiesta nacional, a reinventarnos. Reinventarse para no cambiar nada. Reinventarse para que sigan ganando los mismos.<\/p>\n<p style=\"text-align: left\">La desmoralizante situaci\u00f3n cultural del pa\u00eds no pasa por reinventar nada sino por construir, y la construcci\u00f3n s\u00f3lo es posible desde la creatividad. Grandes dosis de creatividad ser\u00e1n necesarias para establecer nuevos modelos de museos que incorporen en sus salas las voces de un p\u00fablico m\u00e1s diverso. Una enorme creatividad ser\u00e1 necesaria para establecer circuitos y recursos variados desde donde los artistas puedan dejar de ser gestores culturales para volver a ser creadores. Creatividad en may\u00fascula ser\u00e1 necesaria para que los gestores puedan dise\u00f1ar programaciones en las que pagar justamente a m\u00fasicos y actores, dot\u00e1ndoles adem\u00e1s de escenarios dignos. Y mucha creatividad, insisto mucha, ser\u00e1 necesaria para desarrollar otros modelos educativos que ayuden a ni\u00f1as y ni\u00f1os a formarse emocionalmente como futuros ciudadanos con ideas y criterios propios.<\/p>\n<p style=\"text-align: left\">Muchos siguen afirmando con rotundidad que la creatividad est\u00e1 sobrevalorada pero cr\u00e9anme si les digo que esta afirmaci\u00f3n s\u00f3lo encierra una verdad: la sociedad que no es creativa no desarrolla actitud cr\u00edtica y ser\u00e1, por tanto, una sociedad alienada, vac\u00eda y manipulable.\u00a0Cada cual que decida su forma de actuar en \u00e9ste nuevo a\u00f1o que comienza. Yo tengo claro que seguir\u00e9 practicando la creatividad en todas las peque\u00f1as cosas de mi vida sin ninguna necesidad de reinventarme porque como bien dec\u00eda Edith Wharton: \u201cLa creatividad no consiste en una nueva manera, sino en una nueva visi\u00f3n\u201d.<\/p>\n<p style=\"text-align: left\">\u00a1Feliz 2015! Urte berri on!<\/p>\n<p style=\"text-align: left\">*<em><strong>@aitziberurtasun<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><iframe loading=\"lazy\" title=\"\u00bf Qu\u00e9 sabes de creatividad ?\" width=\"660\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/QB85CQkKsPU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: left\"><iframe loading=\"lazy\" title=\"Los enemigos de nuestra Creatividad\" width=\"660\" height=\"371\" src=\"https:\/\/www.youtube.com\/embed\/IXdj_0Xphyw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00bfMe contradigo?, s\u00ed, me contradigo. Soy muchos, contengo multitudes\u00ab. (Walt Whitman) A punto de abandonar este ya viejo a\u00f1o 2014 en el que la cultura ha pasado de estar en un coma de primer estadio a sufrir un coma profundo, una vuelve a descubrir con una mezcla de estupor y mala leche que los peri\u00f3dicos, &hellip; <a href=\"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/2014\/12\/26\/la-creatividad-esta-sobrevalorada-2\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">LA CREATIVIDAD EST\u00c1 SOBREVALORADA<\/span><\/a><\/p>\n","protected":false},"author":83,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3520,3521,3522,3525],"class_list":["post-76","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-arte","tag-creatividad","tag-cultura","tag-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/posts\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":12,"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/posts\/76\/revisions"}],"predecessor-version":[{"id":89,"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/posts\/76\/revisions\/89"}],"wp:attachment":[{"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/media?parent=76"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/categories?post=76"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.noticiasdenavarra.com\/estonoesunblog\/wp-json\/wp\/v2\/tags?post=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}